{"id":685,"date":"2020-08-05T09:51:38","date_gmt":"2020-08-05T07:51:38","guid":{"rendered":"http:\/\/betriebsschau.com\/?page_id=685"},"modified":"2022-06-23T16:02:36","modified_gmt":"2022-06-23T14:02:36","slug":"erfolgreich-selbststaendig-mit-dem-eigenen-unternehmen","status":"publish","type":"page","link":"https:\/\/lebensschau.com\/de\/erfolgreich-selbststaendig-mit-dem-eigenen-unternehmen\/","title":{"rendered":"Erfolgreich selbst\u00e4ndig mit dem eigenen Unternehmen"},"content":{"rendered":"<div id=\"pl-685\"  class=\"panel-layout\" ><div id=\"pg-685-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-685-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-0-0-0\" class=\"so-panel widget panel-first-child\" data-index=\"0\" ><\/div><div id=\"panel-685-0-0-1\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"1\" >\t\t\t<div class=\"textwidget\"><p><center><\/p>\n<h1><strong><span style=\"color: #00599a;\">Erfolgreich selbstst\u00e4ndig mit dem eigenen Unternehmen<br \/>\n<\/span><\/strong><\/h1>\n<p><\/center><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-685-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-685-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"2\" >\t\t\t<div class=\"textwidget\"><p><img decoding=\"async\" class=\"aligncenter size-full wp-image-867\" src=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/raise_new.jpg\" alt=\"\" width=\"750\" srcset=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/raise_new.jpg 631w, https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/raise_new-300x228.jpg 300w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-685-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-685-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-2-0-0\" class=\"so-panel widget panel-first-child\" data-index=\"3\" ><\/div><div id=\"panel-685-2-0-1\" class=\"so-panel widget widget_text\" data-index=\"4\" >\t\t\t<div class=\"textwidget\"><h2>Was kann ich f\u00fcr Sie als Expertin beim Thema erfolgreiche Selbstst\u00e4ndigkeit tun?<\/h2>\n<\/div>\n\t\t<\/div><div id=\"panel-685-2-0-2\" class=\"so-panel widget widget_sow-accordion\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-accordion so-widget-sow-accordion-default-99be652ed941-685\"\n\t\t\t\n\t\t><div>\n\t<div class=\"sow-accordion\">\n\t\t\t<div class=\"sow-accordion-panel\n\t\t\t\t\t\"\n\t\t\t\tdata-anchor-id=\"ist-selbststaendigkeit-eine-option-fuer-mich\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header-container\" role=\"heading\" aria-level=\"2\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header\" tabindex=\"0\" role=\"button\" id=\"accordion-label-ist-selbstst%c3%a4ndigkeit-eine-option-f%c3%bcr-mich\" aria-controls=\"accordion-content-ist-selbstst%c3%a4ndigkeit-eine-option-f%c3%bcr-mich\" aria-expanded=\"false\">\n\t\t\t\t\t\t<div class=\"sow-accordion-title sow-accordion-title-icon-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tIst Selbstst\u00e4ndigkeit eine Option f\u00fcr mich?\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-accordion-open-close-button\">\n\t\t\t\t\t\t\t<div class=\"sow-accordion-open-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf218;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sow-accordion-close-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf209;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div\n\t\t\t\tclass=\"sow-accordion-panel-content\"\n\t\t\t\trole=\"region\"\n\t\t\t\taria-labelledby=\"accordion-label-ist-selbstst%c3%a4ndigkeit-eine-option-f%c3%bcr-mich\"\n\t\t\t\tid=\"accordion-content-ist-selbstst%c3%a4ndigkeit-eine-option-f%c3%bcr-mich\"\n\t\t\t\tstyle=\"display: none;\"\t\t\t>\n\t\t\t\t<div class=\"sow-accordion-panel-border\">\n\t\t\t\t\t<p><b>Ihre Situation:<\/b><br \/>\nSie w\u00e4ren gerne selbstst\u00e4ndig Ihnen fehlt aber die richtige Idee? Sie sind sich nicht sicher ob Sie die richtigen F\u00e4higkeiten mitbringen? Sie versp\u00fcren Existenz\u00e4ngste und m\u00f6chten nicht unter der Br\u00fccke landen? Aber der Wunsch ein eigenes Unternehmen zu gr\u00fcnden taucht einfach immer wieder hartn\u00e4ckig auf?<\/p>\n<p>Mit 29 Jahren habe ich mich erstmals selbstst\u00e4ndig gemacht und es nie bereut. Trotz meines Studium der Betriebswirtschaftslehre und einer anschlie\u00dfenden T\u00e4tigkeit als Firmenkundenberaterin der Deutschen Bank habe ich aber gemerkt, dass es als Unternehmer viel zu lernen gibt und sich auch immer wieder \u00dcberraschungen auftun, die gute Nerven und viel Energie, Ideenreichtum und L\u00f6sungswillen erfordern. Gehen Sie mit mir der spannenden Frage nach ob Sie f\u00fcr dieses Leben geschaffen sind und wie Sie es gegebenenfalls gut angehen.<\/p>\n<p><a href=\"#Kontakt\"><span style=\"color: #000000;\">Alles beginnt mit einem Gespr\u00e4ch.\u00a0Sie erreichen mich <u>hier<\/u><\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"sow-accordion-panel\n\t\t\t\t\t\"\n\t\t\t\tdata-anchor-id=\"die-uebergangszeit-zwischen-anstellung-und-selbststaendigkeit-gestalten\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header-container\" role=\"heading\" aria-level=\"2\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header\" tabindex=\"0\" role=\"button\" id=\"accordion-label-die-%c3%bcbergangszeit-zwischen-anstellung-und-selbstst%c3%a4ndigkeit-gestalten\" aria-controls=\"accordion-content-die-%c3%bcbergangszeit-zwischen-anstellung-und-selbstst%c3%a4ndigkeit-gestalten\" aria-expanded=\"false\">\n\t\t\t\t\t\t<div class=\"sow-accordion-title sow-accordion-title-icon-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tDie \u00dcbergangszeit zwischen Anstellung und Selbstst\u00e4ndigkeit gestalten\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-accordion-open-close-button\">\n\t\t\t\t\t\t\t<div class=\"sow-accordion-open-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf218;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sow-accordion-close-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf209;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div\n\t\t\t\tclass=\"sow-accordion-panel-content\"\n\t\t\t\trole=\"region\"\n\t\t\t\taria-labelledby=\"accordion-label-die-%c3%bcbergangszeit-zwischen-anstellung-und-selbstst%c3%a4ndigkeit-gestalten\"\n\t\t\t\tid=\"accordion-content-die-%c3%bcbergangszeit-zwischen-anstellung-und-selbstst%c3%a4ndigkeit-gestalten\"\n\t\t\t\tstyle=\"display: none;\"\t\t\t>\n\t\t\t\t<div class=\"sow-accordion-panel-border\">\n\t\t\t\t\t<p><b>Ihre Situation:<\/b><br \/>\nSie m\u00f6chten sich selbstst\u00e4ndig machen m\u00fcssen aber aus finanziellen Gr\u00fcnden eine \u00dcbergangszeit einplanen und wissen nicht wie? Sie w\u00fcnschen sich kompetente Begleitung bei der Gestaltung und der Einsch\u00e4tzung von Unw\u00e4gbarkeiten? Sie sind noch unentschlossen ob Sie in Teilzeit angestellt bleiben und nebenher selbstst\u00e4ndig werden m\u00f6chten?<\/p>\n<p>H\u00e4ufig ist es aus finanziellen Gr\u00fcnden nicht m\u00f6glich direkt in eine selbstst\u00e4ndige oder freiberufliche T\u00e4tigkeit zu wechseln. Manchmal gilt es eine \u00dcbergangszeit zu planen und zu gestalten, die sich \u00fcber mehrere Jahre hinziehen kann und einige Fragen aufwirft. Manchmal kann eine nebenberufliche Selbstst\u00e4ndigkeit auch eine Dauerl\u00f6sung darstellen. Als Firmenkundenbetreuerin der Deutschen Bank habe ich gelernt, dass es in der Regel drei bis f\u00fcnf Jahre dauert bis sich ich als Selbstst\u00e4ndiger von meiner Arbeit leben kann. Das kann ich aus eigener Erfahrung best\u00e4tigen - umso wichtiger ist es<br \/>\neinen finanziellen Puffer zu haben und bei Bedarf eine \u00dcbergangszeit zu organisieren.<\/p>\n<p><a href=\"#Kontakt\"><span style=\"color: #000000;\">Alles beginnt mit einem Gespr\u00e4ch.\u00a0Sie erreichen mich <u>hier<\/u><\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"sow-accordion-panel\n\t\t\t\t\t\"\n\t\t\t\tdata-anchor-id=\"erfolgreiche-kommunikation-als-selbststaendiger\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header-container\" role=\"heading\" aria-level=\"2\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header\" tabindex=\"0\" role=\"button\" id=\"accordion-label-erfolgreiche-kommunikation-als-selbstst%c3%a4ndiger\" aria-controls=\"accordion-content-erfolgreiche-kommunikation-als-selbstst%c3%a4ndiger\" aria-expanded=\"false\">\n\t\t\t\t\t\t<div class=\"sow-accordion-title sow-accordion-title-icon-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tErfolgreiche Kommunikation als Selbstst\u00e4ndiger\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-accordion-open-close-button\">\n\t\t\t\t\t\t\t<div class=\"sow-accordion-open-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf218;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sow-accordion-close-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf209;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div\n\t\t\t\tclass=\"sow-accordion-panel-content\"\n\t\t\t\trole=\"region\"\n\t\t\t\taria-labelledby=\"accordion-label-erfolgreiche-kommunikation-als-selbstst%c3%a4ndiger\"\n\t\t\t\tid=\"accordion-content-erfolgreiche-kommunikation-als-selbstst%c3%a4ndiger\"\n\t\t\t\tstyle=\"display: none;\"\t\t\t>\n\t\t\t\t<div class=\"sow-accordion-panel-border\">\n\t\t\t\t\t<p><b>Ihre Situation:<\/b><br \/>\nSie sind fachlich top, aber bei Themen wie Marketing und Mitarbeiterf\u00fchrung noch komplett blank? Sie tun sich schwer bei Verhandlungen mit Kunden, Lieferanten oder Mitarbeitern zu \u00fcberzeugen? Sie m\u00f6chten Ihre Vermeidungsstrategie bei schwierigen Gespr\u00e4chen beenden weil Sie wissen, dass diese nicht zielf\u00fchrend ist?<\/p>\n<p>Sei es mit Kunden, mit Lieferanten oder auch mit Mitarbeitern \u2013 als Selbstst\u00e4ndiger kann erfolgreiche Kommunikation in wichtigen Verhandlungssituationen den entscheidenden Unterschied zwischen Erfolg und Misserfolg ausmachen. Nicht jedem Neu-Selbstst\u00e4ndigen fliegt diese jedoch automatisch zu. Profitieren von meiner jahrzehntelangen Erfahrung bei Verhandlungen aller Art in deutscher und in englischer Sprache und mit Verhandlungspartnern aus aller Welt. Auch hier ist gute Vorbereitung der Schl\u00fcssel zum Erfolg.<\/p>\n<p><a href=\"#Kontakt\"><span style=\"color: #000000;\">Alles beginnt mit einem Gespr\u00e4ch.\u00a0Sie erreichen mich <u>hier<\/u><\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"sow-accordion-panel\n\t\t\t\t\t\"\n\t\t\t\tdata-anchor-id=\"ihre-work-life-balance-als-selbststaendiger\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header-container\" role=\"heading\" aria-level=\"2\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header\" tabindex=\"0\" role=\"button\" id=\"accordion-label-ihre-work-life-balance-als-selbstst%c3%a4ndiger\" aria-controls=\"accordion-content-ihre-work-life-balance-als-selbstst%c3%a4ndiger\" aria-expanded=\"false\">\n\t\t\t\t\t\t<div class=\"sow-accordion-title sow-accordion-title-icon-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tIhre Work-Life-Balance als Selbstst\u00e4ndiger\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-accordion-open-close-button\">\n\t\t\t\t\t\t\t<div class=\"sow-accordion-open-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf218;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sow-accordion-close-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf209;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div\n\t\t\t\tclass=\"sow-accordion-panel-content\"\n\t\t\t\trole=\"region\"\n\t\t\t\taria-labelledby=\"accordion-label-ihre-work-life-balance-als-selbstst%c3%a4ndiger\"\n\t\t\t\tid=\"accordion-content-ihre-work-life-balance-als-selbstst%c3%a4ndiger\"\n\t\t\t\tstyle=\"display: none;\"\t\t\t>\n\t\t\t\t<div class=\"sow-accordion-panel-border\">\n\t\t\t\t\t<p><b>Ihre Situation:<\/b><br \/>\nSie sind ersch\u00f6pft, arbeiten rund um die Uhr, kennen keine Wochenenden mehr und wissen schon gar nicht mehr wann Sie zum letzten Mal Urlaub gemacht haben? Ihre Familie sieht Sie viel zu selten, die Partnerschaft kriselt und Freizeit und Hobbies sind zu Fremdw\u00f6rtern geworden? Es f\u00e4llt Ihnen schwer zu delegieren weil keiner die Arbeiten so gut ausf\u00fchrt wie Sie?<\/p>\n<p>Klar, als Selbstst\u00e4ndige\/r sind Sie selbst und st\u00e4ndig im Einsatz. Das ist am Anfang einer Selbstst\u00e4ndigkeit meist unvermeidlich, hinterl\u00e4sst auf Dauer aber Spuren, die Ihr Privatleben massiv beeintr\u00e4chtigen und Ihre Gesundheit zum Beispiel in Form eines Burnouts gef\u00e4hrden k\u00f6nnen. Lassen Sie uns gemeinsam Ihre Work-Life-Balance unter die Lupe nehmen und die passenden Stellschrauben neu justieren.<\/p>\n<p><a href=\"#Kontakt\"><span style=\"color: #000000;\">Alles beginnt mit einem Gespr\u00e4ch.\u00a0Sie erreichen mich <u>hier<\/u><\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<div class=\"sow-accordion-panel\n\t\t\t\t\t\"\n\t\t\t\tdata-anchor-id=\"change-management-als-selbststaendige-r\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header-container\" role=\"heading\" aria-level=\"2\">\n\t\t\t\t\t<div class=\"sow-accordion-panel-header\" tabindex=\"0\" role=\"button\" id=\"accordion-label-change-management-als-selbstst%c3%a4ndiger\" aria-controls=\"accordion-content-change-management-als-selbstst%c3%a4ndiger\" aria-expanded=\"false\">\n\t\t\t\t\t\t<div class=\"sow-accordion-title sow-accordion-title-icon-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tChange-Management als Selbstst\u00e4ndige\/r\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-accordion-open-close-button\">\n\t\t\t\t\t\t\t<div class=\"sow-accordion-open-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf218;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sow-accordion-close-button\">\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-ionicons\" data-sow-icon=\"&#xf209;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div\n\t\t\t\tclass=\"sow-accordion-panel-content\"\n\t\t\t\trole=\"region\"\n\t\t\t\taria-labelledby=\"accordion-label-change-management-als-selbstst%c3%a4ndiger\"\n\t\t\t\tid=\"accordion-content-change-management-als-selbstst%c3%a4ndiger\"\n\t\t\t\tstyle=\"display: none;\"\t\t\t>\n\t\t\t\t<div class=\"sow-accordion-panel-border\">\n\t\t\t\t\t<p><b>Ihre Situation:<\/b><br \/>\nIhr Unternehmen steckt in der Krise weil Ihr gr\u00f6\u00dfter Lieferant weggebrochen ist? Ihr bester Mitarbeiter hat Sie verlassen? Sie m\u00f6chten Ihr Unternehmen umorganisieren um zukunftsf\u00e4hig zu bleiben?<\/p>\n<p>Zur Selbstst\u00e4ndigkeit geh\u00f6rt auch der erfolgreiche Umgang mit Wandel und der kann manchmal sehr st\u00fcrmisch sein. Da kann es vorkommen, dass Sie in Situationen geraten, bei denen Sie spontan komplett neuen L\u00f6sungen finden m\u00fcssen. Und niemanden haben mit dem Sie sich austauschen k\u00f6nnen. Als Sparringpartner mit \u00fcber 20-j\u00e4hriger Erfahrung in der Selbstst\u00e4ndigkeit stehe ich Ihnen gerne mit meinem umfangreichen Wissen und meiner Kreativit\u00e4t bei der Suche nach L\u00f6sungen zur Verf\u00fcgung.<\/p>\n<p><a href=\"#Kontakt\"><span style=\"color: #000000;\">Alles beginnt mit einem Gespr\u00e4ch.\u00a0Sie erreichen mich <u>hier<\/u><\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<\/div>\n<\/div><\/div><div id=\"panel-685-2-0-3\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"6\" >\t\t\t<div class=\"textwidget\"><h4><strong>Ihr Thema ist nicht dabei?<\/strong>\u00a0Dann lade ich Sie herzlich ein mir eine <a href=\"renate.broeckel@lebensschau.com\"><u>E-mail zu schreiben<\/u><\/a> und eine kostenfreie R\u00fcckmeldung zu Ihrem Thema zu erhalten.<\/h4>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-685-3\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-685-3\" ><div id=\"pgc-685-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-3-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"7\" >\t\t\t<div class=\"textwidget\"><h2><strong><span style=\"color: #005a9a;\">\u00dcber mich<\/span><\/strong><\/h2>\n<p>Meiner Entscheidung mich vor \u00fcber 20 Jahren <strong>selbstst\u00e4ndig zu machen<\/strong> gingen mehrmonatige \u00dcberlegungen voraus. Denn auch heute noch wei\u00df ich genau wieviel Mut es gekostet hat sich gegen die sichere Karriere bei der Bank und f\u00fcr die unsichere Selbstst\u00e4ndigkeit zu entscheiden. Es folgte eine noch l\u00e4ngere Vorbereitungszeit mit der Erstellung eines Business Plans, der Beantragung eines Existenzgr\u00fcndungsdarlehens und vielen weiteren Schritten. Und Jahre des Aufbaus zun\u00e4chst ohne und sp\u00e4ter mit Familie.<\/p>\n<p>Learning by doing bei Verhandlungen in Unternehmen aller Gr\u00f6\u00dfenordnungen bis hin zu multinationalen Konzernen. Und immer wieder Ereignisse von au\u00dfen, die <strong>spontane und teilweise umfassende Anpassungen<\/strong> erfordert haben. Da hie\u00df es auch immer wieder die Nerven behalten, die Mitarbeiter beruhigen und die <strong>Work-Life-Balance<\/strong> nicht verlieren. Mein <strong>Abschluss als Dipl.Kfr.<\/strong> und meine <strong>T\u00e4tigkeit als Firmenkundenbetreuerin<\/strong> der Deutschen Bank haben mir hier gute Startvoraussetzungen mitgegeben. Meine eigene Work-Life-Balance hat von meiner\u00a0<strong>Ausbildung als Entspannungstherapeutin<\/strong>\u00a0und meinem Wissen \u00fcber Achtsamkeit profitiert.<\/p>\n<p>Weitere Informationen zu mir und meinen Ausbildungen finden Sie <a href=\"https:\/\/lebensschau.com\/ueber-mich\/\">hier<\/a>.<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-685-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-685-3-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"8\" >\t\t\t<div class=\"textwidget\"><div class=\"wp-block-spacer\" style=\"height: 60px;\" aria-hidden=\"true\"><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4682\" src=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/06\/renate_business_2022.jpg\" alt=\"\" width=\"250\" height=\"426\" srcset=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/06\/renate_business_2022.jpg 500w, https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/06\/renate_business_2022-176x300.jpg 176w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2409\" src=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/09\/renate_transparent.png\" alt=\"\" width=\"226\" height=\"58\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-685-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-685-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-4-0-0\" class=\"so-panel widget panel-first-child panel-last-child\" data-index=\"9\" ><\/div><\/div><\/div><div id=\"pg-685-5\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-685-5\" ><div id=\"pgc-685-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-5-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"10\" >\t\t\t<div class=\"textwidget\"><h2><span style=\"color: #005a9a;\">Screenshots von 2 meiner Bewertungen:<\/span><\/h2>\n<p>Weitere finden Sie <a href=\"https:\/\/www.google.de\/search?client=safari&amp;sxsrf=ALeKk01MTQJPm986UF-om7WHjluHepL2Ew%3A1596302172568&amp;source=hp&amp;ei=XKMlX97hH-yfjLsPiPOgyA8&amp;q=Renate+Br%C3%B6ckel+Lebensschau&amp;oq=Renate+Br%C3%B6ckel+Lebensschau\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4558\" src=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/lindsay_deutsch.jpg\" alt=\"\" width=\"1342\" height=\"430\" srcset=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/lindsay_deutsch.jpg 1342w, https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/lindsay_deutsch-300x96.jpg 300w, https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/lindsay_deutsch-1024x328.jpg 1024w, https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/lindsay_deutsch-768x246.jpg 768w\" sizes=\"auto, (max-width: 1342px) 100vw, 1342px\" \/><\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-773\" src=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/Bildschirmfoto-2020-08-24-um-11.13.31.png\" alt=\"\" width=\"1320\" height=\"288\" srcset=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/Bildschirmfoto-2020-08-24-um-11.13.31.png 1320w, https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/Bildschirmfoto-2020-08-24-um-11.13.31-300x65.png 300w, https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/Bildschirmfoto-2020-08-24-um-11.13.31-1024x223.png 1024w, https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/08\/Bildschirmfoto-2020-08-24-um-11.13.31-768x168.png 768w\" sizes=\"auto, (max-width: 1320px) 100vw, 1320px\" \/><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-685-6\"  class=\"panel-grid panel-has-style\" ><div id=\"Kontakt\" class=\"panel-row-style panel-row-style-for-685-6\" ><div id=\"pgc-685-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-6-0-0\" class=\"so-panel widget panel-first-child\" data-index=\"11\" ><\/div><div id=\"panel-685-6-0-1\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"12\" >\t\t\t<div class=\"textwidget\"><div class=\"wp-block-spacer\" style=\"height: 30px;\" aria-hidden=\"true\"><\/div>\n<h2><span style=\"color: #005a9a;\">Alles beginnt mit einem Gespr\u00e4ch. Finden Sie mit meiner Unterst\u00fctzung die passenden L\u00f6sungen f\u00fcr Ihre selbstst\u00e4ndige T\u00e4tigkeit. Das Vorgespr\u00e4ch ist gratis und auch danach gehen Sie keine vertragliche Bindung ein und k\u00f6nnen die Zahl der Termine frei bestimmen.\u00a0<\/span><span style=\"color: #005a9a;\">Nehmen Sie noch heute Kontakt auf:<\/span><\/h2>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-685-6-1\"  class=\"panel-grid-cell\" ><div id=\"panel-685-6-1-0\" class=\"so-panel widget panel-first-child\" data-index=\"13\" ><\/div><div id=\"panel-685-6-1-1\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"14\" >\t\t\t<div class=\"textwidget\"><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4601\" src=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/renate_2022_4.png\" alt=\"\" width=\"400\" height=\"421\" srcset=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/renate_2022_4.png 400w, https:\/\/lebensschau.com\/wp-content\/uploads\/2022\/05\/renate_2022_4-285x300.png 285w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1755\" src=\"https:\/\/lebensschau.com\/wp-content\/uploads\/2020\/09\/renate_mistral_blau.jpg\" alt=\"\" width=\"227\" height=\"58\" \/><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-685-7\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-685-7\" data-stretch-type=\"full\" ><div id=\"pgc-685-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-685-7-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"15\" >\t\t\t<div class=\"textwidget\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/685#wpcf7-f5-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div id=\"responsive-form\" class=\"clearfix\">\n\t<div class=\"form-row\">\n\t\t<div class=\"column-half\">\n\t\t\t<h3>\n\t\t\t\t<font color=\"#000000\">Ihr Name (Pflichtfeld)\n\t\t\t\t<\/font>\n\t\t\t<\/h3>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"vorname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"vorname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<h3>\n\t\t\t\t<font color=\"#000000\">Ihre E-mail (Pflichtfeld)\n\t\t\t\t<\/font>\n\t\t\t<\/h3>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<h3>\n\t\t\t\t<font color=\"#000000\">Ihr Anliegen:\n\t\t\t\t<\/font>\n\t\t\t<\/h3>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<font color=\"#000000\"> Bitte vor Versand die Box anklicken (Pflichtfeld):\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-827\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-827\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Datenschutz ist mir wichtig. Ihre Daten werden nur zur Kontaktaufnahme verwendet und nicht weitergegeben. N\u00e4heres zum Datenschutz finden Sie <a href=\"https:\/\/lebensschau.com\/datenschutz\/\">hier<\/a>.\n\t\t\t\t<\/p>\n\t\t\t<\/font>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Senden\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><!--end responsive-form--><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Erfolgreich selbstst\u00e4ndig mit dem eigenen Unternehmen<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-685","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/pages\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/comments?post=685"}],"version-history":[{"count":90,"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/pages\/685\/revisions"}],"predecessor-version":[{"id":4703,"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/pages\/685\/revisions\/4703"}],"wp:attachment":[{"href":"https:\/\/lebensschau.com\/de\/wp-json\/wp\/v2\/media?parent=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}